{"id":8860,"date":"2022-06-14T18:17:01","date_gmt":"2022-06-14T18:17:01","guid":{"rendered":"https:\/\/www.johnbean.com\/eu-de\/?page_id=8860"},"modified":"2026-04-22T14:42:30","modified_gmt":"2026-04-22T14:42:30","slug":"t5325-b-2s","status":"publish","type":"page","link":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/","title":{"rendered":"T5325B 2S"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8860\" class=\"elementor elementor-8860\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56246854 elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"56246854\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1970d8a8\" data-id=\"1970d8a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25e965da elementor-widget elementor-widget-image\" data-id=\"25e965da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2170\" height=\"942\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-header.jpg\" class=\"attachment-full size-full wp-image-8866\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6cd244 elementor-widget elementor-widget-image\" data-id=\"a6cd244\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.johnbean.com\/eu-de\/find-a-representative\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"30\" height=\"223\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/07\/HANDLERSUCHE-1.png\" class=\"attachment-large size-large wp-image-15861\" alt=\"H\u00c4NDLERSUCHE\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de7a587 elementor-widget elementor-widget-image\" data-id=\"1de7a587\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.johnbean.com\/eu-de\/get-a-quote\/?_m=T5325%202S\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"477\" height=\"620\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2024\/05\/T5325-2S-text-block-de.png\" class=\"attachment-large size-large wp-image-23119\" alt=\"\" srcset=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2024\/05\/T5325-2S-text-block-de.png 477w, https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2024\/05\/T5325-2S-text-block-de-231x300.png 231w\" sizes=\"(max-width: 477px) 100vw, 477px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb49327 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"cb49327\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff9331f\" data-id=\"ff9331f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c26b21e elementor-widget elementor-widget-image\" data-id=\"c26b21e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.johnbean.com\/eu-de\/get-a-quote\/?_m=T5325%202S\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/07\/T5325B-2S-header-1.jpg\" class=\"attachment-full size-full wp-image-14884\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34a172e elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"34a172e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.johnbean.com\/eu-de\/find-a-representative\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"223\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/07\/HANDLERSUCHE-1.png\" class=\"attachment-full size-full wp-image-15861\" alt=\"H\u00c4NDLERSUCHE\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-236ad48d elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"236ad48d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f85e785\" data-id=\"6f85e785\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf2a3df elementor-widget elementor-widget-text-editor\" data-id=\"bf2a3df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>OEM TRUSTED EQUIPMENT: <\/b>CHRYSLER | DODGE | JEEP | RAM | VOLVO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12ebd2ff elementor-section-full_width elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"12ebd2ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e8ced47\" data-id=\"1e8ced47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75a10abd elementor-widget elementor-widget-text-editor\" data-id=\"75a10abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"#description\">BEZEICHNUNG<\/a> | <a href=\"#versions\">VERSIONEN<\/a> | <a href=\"#features\">MERKMALE<\/a> | <a href=\"#adfeatures\"> ZUS\u00c4TZLICHE MERKMALE <\/a> | <a href=\"#downloads\">HERUNTERLADEN<\/a> | <a href=\"#tech\"> TECHNISCHE DATEN <\/a> | <a href=\"#acc\">ZUBEH\u00d6R<\/a> | <a href=\"#related\">VERWANDTE PRODUKTE<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37ee049c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"37ee049c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41a2801a\" data-id=\"41a2801a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-655a51c0 elementor-widget elementor-widget-heading\" data-id=\"655a51c0\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"description\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325 2S<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48ef97be elementor-widget elementor-widget-text-editor\" data-id=\"48ef97be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Robust und zuverl\u00e4ssig vereint die T5325 2S von John Bean<sup>\u00ae<\/sup> die n\u00fctzlichen Merkmale f\u00fcr eine effiziente Reifenmontage und -demontage.<\/p><p>Praktisch und bedienerfreundlich bietet die T5325 2S mit der bew\u00e4hrten, pneumatisch kippbaren Montages\u00e4ule ausreichend Platz, um das Rad bequem auf dem Spannteller zu positionieren. Sie verf\u00fcgt \u00fcber die PROspeed\u2122-Technik, die das aufgebrachte Drehmoment \u00fcberwacht und dementsprechend die maximale Drehzahl w\u00e4hlt &#8211; das bedeutet maximale Sicherheit f\u00fcr das Rad. Ergonomisch und effektiv werden Standardreifen und Reifen mit einem Querschnitt &gt; 55 mit dem pedalbet\u00e4tigten seitlichen Abdr\u00fccker abgedr\u00fcckt. Mit der dreiteiligen pneumatischen Montagehilfe kann ein einziger Benutzer selbst schwierig handbarbare Niederquerschnittreifen schnell und einfach demontieren bzw. montieren. Bedienerfreundlich, aber sehr effektiv gelingt das Wulstsetzen mit der externen F\u00fcllsto\u00dfvorrichtung.<\/p><p>Die T5325 2S bietet alle zukunftsweisenden Merkmale, die Sie im modernen Reifenservice ben\u00f6tigen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78efa670 elementor-widget elementor-widget-heading\" data-id=\"78efa670\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"versions\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VERSIONEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e1593b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5e1593b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-379f3a5\" data-id=\"379f3a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7f49f7 elementor-widget elementor-widget-image\" data-id=\"d7f49f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"157\" height=\"135\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325-2S.jpg\" class=\"attachment-large size-large wp-image-8884\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-faa2ae3\" data-id=\"faa2ae3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fbdfc6 elementor-widget elementor-widget-text-editor\" data-id=\"1fbdfc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>T5320 2S: Version ohne F\u00fcllsto\u00dfvorrichtung und pneumatische Montagehilfe<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbc74c6 elementor-widget elementor-widget-heading\" data-id=\"dbc74c6\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"features\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MERKMALE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2fe16b8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2fe16b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6c6812ef\" data-id=\"6c6812ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a571209 elementor-widget elementor-widget-image\" data-id=\"1a571209\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"296\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/TILT-TOWER.jpg\" class=\"attachment-large size-large wp-image-2325\" alt=\"\" srcset=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/TILT-TOWER.jpg 459w, https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/TILT-TOWER-300x193.jpg 300w\" sizes=\"(max-width: 459px) 100vw, 459px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ccf35fb elementor-widget elementor-widget-text-editor\" data-id=\"3ccf35fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>PNEUMATISCH KIPPBARE MONTAGES\u00c4ULE <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c8bd879 elementor-widget elementor-widget-text-editor\" data-id=\"1c8bd879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dank der pneumatisch kippbaren Montages\u00e4ule entsteht ausreichend Platz, das Rad auf dem Spannteller zu positionieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-650da54\" data-id=\"650da54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a2f8b53 elementor-widget elementor-widget-image\" data-id=\"7a2f8b53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"296\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/08\/prospeed.png\" class=\"attachment-large size-large wp-image-18233\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d95fefd elementor-widget elementor-widget-text-editor\" data-id=\"4d95fefd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>PROspeed\u2122 <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6442debb elementor-widget elementor-widget-text-editor\" data-id=\"6442debb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die innovative Technik zur Optimierung des Drehmomentes mit automatischer Einstellung der entsprechenden maximal m\u00f6glichen Drehzahl &#8211; sicher und effizient.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2f998d9\" data-id=\"2f998d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52523d5 elementor-widget elementor-widget-image\" data-id=\"52523d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"296\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/ON-FLOOR-BEAD-BREAKER-PEDAL-OPERATED-1.jpg\" class=\"attachment-large size-large wp-image-8890\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a765e17 elementor-widget elementor-widget-text-editor\" data-id=\"a765e17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>BODEN-ABDR\u00dcCKER (PEDALBET\u00c4TIGT) <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9617f78 elementor-widget elementor-widget-text-editor\" data-id=\"9617f78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die konventionelle seitliche Abdr\u00fcckschaufel mit ergonomischer Pedalsteuerung ist die schnellste L\u00f6sung f\u00fcr Standardreifen sowie Reifen mit weicher Flanke und einem Querschnitt &gt; 55<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-33feda53\" data-id=\"33feda53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10ff27f1 elementor-widget elementor-widget-image\" data-id=\"10ff27f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"296\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/PNEUMATIC-BEAD-ASSIST.jpg\" class=\"attachment-large size-large wp-image-8892\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a0d02b5 elementor-widget elementor-widget-text-editor\" data-id=\"4a0d02b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>PNEUMATISCHE MONTAGEHILFE <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46bbcb17 elementor-widget elementor-widget-text-editor\" data-id=\"46bbcb17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere dreiteilige pneumatische Montagehilfe besteht aus einer oberen Rolle, dem Niederdr\u00fccker und einer Demontierscheibe zum Heben des Wulstes. Damit ist es f\u00fcr einen einzelnen Benutzer ein Leichtes, Niederquerschnitt- und UHP-Reifen zu montieren und zu demontieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-369760e3 elementor-widget elementor-widget-heading\" data-id=\"369760e3\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"adfeatures\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ZUS\u00c4TZLICHE MERKMALE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7b6f3920 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7b6f3920\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7d47d95b\" data-id=\"7d47d95b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8621561 elementor-widget elementor-widget-image\" data-id=\"8621561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"296\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/TOP-SIDE-BEAD-SEATER-2.jpg\" class=\"attachment-large size-large wp-image-8611\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a30bc2e elementor-widget elementor-widget-text-editor\" data-id=\"a30bc2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>EXTERNE F\u00dcLLSTO\u00dfVORRICHTUNG <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-132d394 elementor-widget elementor-widget-text-editor\" data-id=\"132d394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese ergonomische Handd\u00fcse gibt einen F\u00fcllsto\u00df in den Reifen, damit die W\u00fclste korrekt am Felgenhorn anliegen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-15a7f68e\" data-id=\"15a7f68e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-222c37b4\" data-id=\"222c37b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-19661256\" data-id=\"19661256\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c83857c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2c83857c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26bc0b4f\" data-id=\"26bc0b4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39e3de7d elementor-widget elementor-widget-image\" data-id=\"39e3de7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2169\" height=\"1221\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-action-pic.jpg\" class=\"attachment-full size-full wp-image-8900\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-179400d4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"179400d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fd7d9b2\" data-id=\"1fd7d9b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a48ae2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"39a48ae2\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"downloads\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-447c274 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"447c274\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1ce537e4\" data-id=\"1ce537e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33596bf elementor-widget elementor-widget-heading\" data-id=\"33596bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HERUNTERLADEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-462f1702 elementor-widget elementor-widget-image\" data-id=\"462f1702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/media.johnbean.com\/getpdf.php?p=t5325B%202S&#038;r=7\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/media.johnbean.com\/getposter.php?p=t5325B%202S&amp;r=7\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c858b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"50c858b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/media.johnbean.com\/getpdf.php?p=t5325B%202S&#038;r=7\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HERUNTERLADEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5911bce\" data-id=\"5911bce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-978b4c2 elementor-widget elementor-widget-spacer\" data-id=\"978b4c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-990b62b elementor-widget elementor-widget-image\" data-id=\"990b62b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/media.johnbean.com\/getmedia.php?p=T5325B%202S&#038;r=7\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/media.johnbean.com\/getmediaposter.php?p=T5325B%202S&amp;r=7\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b466039 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b466039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/media.johnbean.com\/getmedia.php?p=T5325B%202S&#038;r=7\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HERUNTERLADEN<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2ee00899\" data-id=\"2ee00899\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2eb41635 elementor-widget elementor-widget-heading\" data-id=\"2eb41635\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"tech\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TECHNISCHE DATEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58a43635 elementor-widget elementor-widget-text-editor\" data-id=\"58a43635\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Max. Felgendurchmesser<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b817976 elementor-widget elementor-widget-text-editor\" data-id=\"3b817976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>24&#8243; | 61cm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f62fa83 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4f62fa83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1953d3b3 elementor-widget elementor-widget-text-editor\" data-id=\"1953d3b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Max. Reifenbreite<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-137590a1 elementor-widget elementor-widget-text-editor\" data-id=\"137590a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>13&#8243; | 33cm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4598b1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4598b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b803b40 elementor-widget elementor-widget-text-editor\" data-id=\"b803b40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Max. Felgenbreite<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14bf2450 elementor-widget elementor-widget-text-editor\" data-id=\"14bf2450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>12&#8243; | 31cm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2263fd0a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2263fd0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47447a39 elementor-widget elementor-widget-text-editor\" data-id=\"47447a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Max. Raddurchmesser<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dcde6e7 elementor-widget elementor-widget-text-editor\" data-id=\"1dcde6e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>39&#8243; | 100cm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40f3ec9d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"40f3ec9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cd6ce58 elementor-widget elementor-widget-text-editor\" data-id=\"1cd6ce58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tragkraft \/ Radheber<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-573fc43b elementor-widget elementor-widget-text-editor\" data-id=\"573fc43b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>154 lbs. | 70 kg<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5f2d86 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6a5f2d86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5410b377 elementor-widget elementor-widget-text-editor\" data-id=\"5410b377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Elektroanschluss<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f20433 elementor-widget elementor-widget-text-editor\" data-id=\"5f20433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>230V 1ph 50-60Hz 16A<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2f7dc8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6e2f7dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d69efb elementor-widget elementor-widget-text-editor\" data-id=\"2d69efb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erforderlicher Druckluftanschluss<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2a8edc elementor-widget elementor-widget-text-editor\" data-id=\"3c2a8edc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>116-174 PSI | 8-12 bar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52b4c9c4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"52b4c9c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38a04003 elementor-widget elementor-widget-text-editor\" data-id=\"38a04003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abmessungen HxBxT<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d2b1edb elementor-widget elementor-widget-text-editor\" data-id=\"6d2b1edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>63&#8243;x73&#8243;x70&#8243; | 160x185X178cm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d06ad7a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d06ad7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-154b57a4\" data-id=\"154b57a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ef067fc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6ef067fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-69fb8ca7\" data-id=\"69fb8ca7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-688b7aa5 elementor-widget elementor-widget-heading\" data-id=\"688b7aa5\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"acc\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">STANDARDZUBEH\u00d6R IM LIEFERUMFANG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-56953aad elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"56953aad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-28d09a94\" data-id=\"28d09a94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-567d96c4 elementor-widget elementor-widget-image\" data-id=\"567d96c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/Lube-Brush.jpg\" class=\"attachment-full size-full wp-image-2235\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Pinsel f\u00fcr Montagepaste<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-5b2007f8\" data-id=\"5b2007f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76330154 elementor-widget elementor-widget-image\" data-id=\"76330154\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/10\/4025460.png\" class=\"attachment-full size-full wp-image-20245\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Halter f\u00fcr Montagekastenbeh\u00e4lter (5 kg)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-71a4a316\" data-id=\"71a4a316\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31c8f897 elementor-widget elementor-widget-image\" data-id=\"31c8f897\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/34415-Bead-Lever-Plus.png\" class=\"attachment-full size-full wp-image-21151\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Montiereisen WAVE PLUS<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-3c7e8d34\" data-id=\"3c7e8d34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76f6f902 elementor-widget elementor-widget-image\" data-id=\"76f6f902\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/10\/Bead-lever-protector-plus.png\" class=\"attachment-full size-full wp-image-19447\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Kunststoffschutz f\u00fcr Montiereisen WAVE PLUS<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-6189a03e\" data-id=\"6189a03e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43ebbd8d elementor-widget elementor-widget-image\" data-id=\"43ebbd8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/31765-Bead-Breaker-Blade-Protector.png\" class=\"attachment-full size-full wp-image-21290\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Kunststoffschutz f\u00fcr Abdr\u00fcckschaufel<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-47c715bb\" data-id=\"47c715bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8db242d elementor-widget elementor-widget-image\" data-id=\"8db242d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/EAK0317G12A-Light-Alloy-Rim-Protectors-1.png\" class=\"attachment-full size-full wp-image-21326\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Kunststoffschutze f\u00fcr Spannklauen - vorne &amp; hinten<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-38a9f6b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"38a9f6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-db85405\" data-id=\"db85405\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26fe3d33 elementor-widget elementor-widget-image\" data-id=\"26fe3d33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/Plastic-Rim-Protector-Clip-on-Type.jpg\" class=\"attachment-full size-full wp-image-8921\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Kunststofffelgenschutz<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-4fa2cc3\" data-id=\"4fa2cc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-18ee0c2\" data-id=\"18ee0c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-be0d129\" data-id=\"be0d129\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-1a59767\" data-id=\"1a59767\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-2efb01f\" data-id=\"2efb01f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8aea39 elementor-widget elementor-widget-text-editor\" data-id=\"b8aea39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>OPTIONALES ZUBEH\u00d6R<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a35ceea elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a35ceea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-3810fc2\" data-id=\"3810fc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1604eaa elementor-widget elementor-widget-image\" data-id=\"1604eaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/Wheel-Lift-CW.png\" class=\"attachment-full size-full wp-image-21213\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Radheber<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-1910da7\" data-id=\"1910da7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18fbd92 elementor-widget elementor-widget-image\" data-id=\"18fbd92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/4026290-Roller-Board.png\" class=\"attachment-full size-full wp-image-21283\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Rollenbrett<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-33561a2\" data-id=\"33561a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fade757 elementor-widget elementor-widget-image\" data-id=\"fade757\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/4028228-Quick-Exchange-Device-with-Mounting-Head.png\" class=\"attachment-full size-full wp-image-21215\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Schnellwechselvorrichtung mit Montagekopf<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-a57cf48\" data-id=\"a57cf48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff11bf2 elementor-widget elementor-widget-image\" data-id=\"ff11bf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/6-inch-Jaw-Adaptors-for-Centre-Type-Jaws.jpg\" class=\"attachment-full size-full wp-image-8938\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">6\" Zusatzspannklauen f\u00fcr Spannklauen<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-0d2e1ad\" data-id=\"0d2e1ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a18d8cd elementor-widget elementor-widget-image\" data-id=\"a18d8cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/Light-Truck-Adaptors-for-Non-sliding-Jawsjaws.png\" class=\"attachment-full size-full wp-image-21244\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Zusatzspannklauen LLkw-R\u00e4der f\u00fcr Spannklauen<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-80c171b\" data-id=\"80c171b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57838f4 elementor-widget elementor-widget-image\" data-id=\"57838f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/MH-Tractor-Kit-2.jpg\" class=\"attachment-full size-full wp-image-8785\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Zugvorrichtung<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81fe591 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"81fe591\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-c46d1c5\" data-id=\"c46d1c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4caf95e elementor-widget elementor-widget-image\" data-id=\"4caf95e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/4028568-Motorcycle-and-ATV-Jaws-Adaptors.png\" class=\"attachment-full size-full wp-image-21285\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Zusatzspannklauen Mot &amp; ATV f\u00fcr Schiebeklauen<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-c99ade3\" data-id=\"c99ade3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-498527d elementor-widget elementor-widget-image\" data-id=\"498527d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/4013706-Motorcycle-Mounting-Head.png\" class=\"attachment-full size-full wp-image-21204\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Motorrad-Montagekopf<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-d97dcd4\" data-id=\"d97dcd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-519c642 elementor-widget elementor-widget-image\" data-id=\"519c642\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/4008755-Motorcycle-Bead-Breaker-Blade.png\" class=\"attachment-full size-full wp-image-21291\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Zusatzabdr\u00fcckschaufel f\u00fcr Motorradr\u00e4der<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-857dfb4\" data-id=\"857dfb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1210c45 elementor-widget elementor-widget-image\" data-id=\"1210c45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/4029113-Slip-on-Shoe.png\" class=\"attachment-full size-full wp-image-21286\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Aufsteckschuh<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-7e1b63f\" data-id=\"7e1b63f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18288d0 elementor-widget elementor-widget-image\" data-id=\"18288d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/Plastic-Tyre-Protector-Clip-on-Type-1.jpg\" class=\"attachment-full size-full wp-image-8932\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Kunststoffreifenschutz<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-815d30f\" data-id=\"815d30f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e9127a elementor-widget elementor-widget-image\" data-id=\"5e9127a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/Smart-Bead-Spacer-Tail-1.jpg\" class=\"attachment-full size-full wp-image-8934\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Wulstniederhalter Smart Bead Spacer <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d15f37b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d15f37b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-2b6b581\" data-id=\"2b6b581\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94ce2ad elementor-widget elementor-widget-image\" data-id=\"94ce2ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"277\" height=\"220\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/12\/4003444-Bead-Depressing-Tool-MX.png\" class=\"attachment-full size-full wp-image-21211\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Wulstniederhalter <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-c8cfeac\" data-id=\"c8cfeac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-f47af8d\" data-id=\"f47af8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-a27e325\" data-id=\"a27e325\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-073ea2a\" data-id=\"073ea2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-5d5e92c\" data-id=\"5d5e92c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4878e2fc elementor-widget elementor-widget-heading\" data-id=\"4878e2fc\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"related\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VERWANDTE PRODUKTE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-70bbca50 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"70bbca50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-47dd748c\" data-id=\"47dd748c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77daadcc elementor-widget elementor-widget-shortcode\" data-id=\"77daadcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='white' style='background:rgb(255, 255, 255); border:solid 1px rgb(255, 255, 255); border-radius:5px; padding:8px 8px 8px 8px;'>\n<div id='sample_slider' class='owl-carousel sa_owl_theme autohide-arrows' data-slider-id='sample_slider' style='visibility:hidden;'>\n<div id='sample_slider_slide01' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t7800-p\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9536 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T7800P-1.jpg\" alt=\"T7800P\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T7800P<\/p><\/div>\n<div id='sample_slider_slide02' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-24394 aligncenter\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/t7700b_carousel-259x300.jpg\" alt=\"\" width=\"259\" height=\"300\" srcset=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/t7700b_carousel-259x300.jpg 259w, https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/t7700b_carousel.jpg 301w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/><\/p>\r\n<p style=\"text-align: center\">T7700B<\/p><\/div>\n<div id='sample_slider_slide03' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5545-b-2s-plus\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9529 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5545B-2S-PLUS-3.jpg\" alt=\"T5545B-2S-PLUS\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T5545B-2S-PLUS<\/p><\/div>\n<div id='sample_slider_slide04' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5345-b-2s-plus\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9527 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5345B-2S-Plus.jpg\" alt=\"T5345B-2S-Plus\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T5345B-2S-Plus<\/p><\/div>\n<div id='sample_slider_slide05' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9525 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-2.jpg\" alt=\"T5325B-2S\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T5325-2S<\/p><\/div>\n<div id='sample_slider_slide06' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5300-b\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9523 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5300B-2.jpg\" alt=\"T5300B\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T5300B<\/p><\/div>\n<div id='sample_slider_slide07' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t1300-b\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9521 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T1300B-1.jpg\" alt=\"T1300B\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T1300B<\/p><\/div>\n<div id='sample_slider_slide08' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t8058wl\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9541 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T8058-WL-1.jpg\" alt=\"T8058-WL\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T8058-WL<\/p><\/div>\n<div id='sample_slider_slide09' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t8056\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9539 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T8056-1.jpg\" alt=\"T8056\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T8056<\/p><\/div>\n<div id='sample_slider_slide10' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t8026\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-20279 size-medium\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/10\/8026Related-Product-Thumbs-259x300.jpg\" alt=\"T8026\" width=\"259\" height=\"300\" srcset=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/10\/8026Related-Product-Thumbs-259x300.jpg 259w, https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/10\/8026Related-Product-Thumbs.jpg 301w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T8026<\/p><\/div>\n<div id='sample_slider_slide11' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; background-color:rgb(255, 255, 255); '><p style=\"text-align: center\"><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5600\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9531 size-full\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5600-1.jpg\" alt=\"T5600\" width=\"301\" height=\"348\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T5600<\/p><\/div>\n<div id='sample_slider_slide12' class='sa_hover_container' style='padding:5% 5%; margin:0px 0%; '><p><a href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5565b-2s\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-23314 aligncenter\" src=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/T5565Bslider-259x300.png\" alt=\"\" width=\"259\" height=\"300\" srcset=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/T5565Bslider-259x300.png 259w, https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/01\/T5565Bslider.png 301w\" sizes=\"(max-width: 259px) 100vw, 259px\" \/><\/a><\/p>\r\n<p style=\"text-align: center\">T5565B 2S Plus<\/p><\/div>\n<\/div>\n<\/div>\n<script type='text\/javascript'>\n\tjQuery(document).ready(function() {\n\t\tjQuery('#sample_slider').owlCarousel({\n\t\t\tresponsive:{\n\t\t\t\t0:{ items:1 },\n\t\t\t\t480:{ items:2 },\n\t\t\t\t768:{ items:3 },\n\t\t\t\t980:{ items:6 },\n\t\t\t\t1200:{ items:6 },\n\t\t\t\t1500:{ items:6 }\n\t\t\t},\n\t\t\tautoplay : true,\n\t\t\tautoplayTimeout : 4000,\n\t\t\tautoplayHoverPause : true,\n\t\t\tsmartSpeed : 300,\n\t\t\tfluidSpeed : 300,\n\t\t\tautoplaySpeed : 300,\n\t\t\tnavSpeed : 300,\n\t\t\tdotsSpeed : 300,\n\t\t\tloop : true,\n\t\t\tnav : true,\n\t\t\tnavText : ['Previous','Next'],\n\t\t\tdots : false,\n\t\t\tresponsiveRefreshRate : 200,\n\t\t\tslideBy : 1,\n\t\t\tmergeFit : true,\n\t\t\tautoHeight : false,\n\t\t\tmouseDrag : true,\n\t\t\ttouchDrag : true\n\t\t});\n\t\tjQuery('#sample_slider').css('visibility', 'visible');\n\t\tsa_resize_sample_slider();\n\t\twindow.addEventListener('resize', sa_resize_sample_slider);\n\t\tfunction sa_resize_sample_slider() {\n\t\t\tvar min_height = '50';\n\t\t\tvar win_width = jQuery(window).width();\n\t\t\tvar slider_width = jQuery('#sample_slider').width();\n\t\t\tif (win_width < 480) {\n\t\t\t\tvar slide_width = slider_width \/ 1;\n\t\t\t} else if (win_width < 768) {\n\t\t\t\tvar slide_width = slider_width \/ 2;\n\t\t\t} else if (win_width < 980) {\n\t\t\t\tvar slide_width = slider_width \/ 3;\n\t\t\t} else if (win_width < 1200) {\n\t\t\t\tvar slide_width = slider_width \/ 6;\n\t\t\t} else if (win_width < 1500) {\n\t\t\t\tvar slide_width = slider_width \/ 6;\n\t\t\t} else {\n\t\t\t\tvar slide_width = slider_width \/ 6;\n\t\t\t}\n\t\t\tslide_width = Math.round(slide_width);\n\t\t\tvar slide_height = '0';\n\t\t\tif (min_height == 'aspect43') {\n\t\t\t\tslide_height = (slide_width \/ 4) * 3;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t} else if (min_height == 'aspect169') {\n\t\t\t\tslide_height = (slide_width \/ 16) * 9;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t} else {\n\t\t\t\tslide_height = (slide_width \/ 100) * min_height;\t\t\t\tslide_height = Math.round(slide_height);\n\t\t\t}\n\t\t\tjQuery('#sample_slider .owl-item .sa_hover_container').css('min-height', slide_height+'px');\n\t\t}\n\t\tvar owl_goto = jQuery('#sample_slider');\n\t\tjQuery('.sample_slider_goto1').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 0);\n\t\t});\n\t\tjQuery('.sample_slider_goto2').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 1);\n\t\t});\n\t\tjQuery('.sample_slider_goto3').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 2);\n\t\t});\n\t\tjQuery('.sample_slider_goto4').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 3);\n\t\t});\n\t\tjQuery('.sample_slider_goto5').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 4);\n\t\t});\n\t\tjQuery('.sample_slider_goto6').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 5);\n\t\t});\n\t\tjQuery('.sample_slider_goto7').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 6);\n\t\t});\n\t\tjQuery('.sample_slider_goto8').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 7);\n\t\t});\n\t\tjQuery('.sample_slider_goto9').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 8);\n\t\t});\n\t\tjQuery('.sample_slider_goto10').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 9);\n\t\t});\n\t\tjQuery('.sample_slider_goto11').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 10);\n\t\t});\n\t\tjQuery('.sample_slider_goto12').click(function(event){\n\t\t\towl_goto.trigger('to.owl.carousel', 11);\n\t\t});\n\t\tvar resize_2240 = jQuery('.owl-carousel');\n\t\tresize_2240.on('initialized.owl.carousel', function(e) {\n\t\t\tif (typeof(Event) === 'function') {\n\t\t\t\twindow.dispatchEvent(new Event('resize'));\n\t\t\t} else {\n\t\t\t\tvar evt = window.document.createEvent('UIEvents');\n\t\t\t\tevt.initUIEvent('resize', true, false, window, 0);\n\t\t\t\twindow.dispatchEvent(evt);\n\t\t\t}\n\t\t});\n\t});\n<\/script>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>OEM TRUSTED EQUIPMENT: CHRYSLER | DODGE | JEEP | RAM | VOLVO BEZEICHNUNG | VERSIONEN | MERKMALE | ZUS\u00c4TZLICHE MERKMALE | HERUNTERLADEN | TECHNISCHE DATEN | ZUBEH\u00d6R | VERWANDTE PRODUKTE Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325 2S Robust und zuverl\u00e4ssig vereint die T5325 2S von John Bean\u00ae die n\u00fctzlichen Merkmale f\u00fcr eine effiziente Reifenmontage und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":816,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"on","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"off","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-8860","page","type-page","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325B 2S | John Bean<\/title>\n<meta name=\"description\" content=\"Built to get the job done, the John Bean\u00ae T5325B 2S combines all the helpful features you need to change tyres the right way.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325B 2S | John Bean\" \/>\n<meta property=\"og:description\" content=\"Built to get the job done, the John Bean\u00ae T5325B 2S combines all the helpful features you need to change tyres the right way.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/\" \/>\n<meta property=\"og:site_name\" content=\"John Bean\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T14:42:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2170\" \/>\n\t<meta property=\"og:image:height\" content=\"942\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/\",\"url\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/\",\"name\":\"Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325B 2S | John Bean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/T5325B-2S-header.jpg\",\"datePublished\":\"2022-06-14T18:17:01+00:00\",\"dateModified\":\"2026-04-22T14:42:30+00:00\",\"description\":\"Built to get the job done, the John Bean\u00ae T5325B 2S combines all the helpful features you need to change tyres the right way.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/T5325B-2S-header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/T5325B-2S-header.jpg\",\"width\":2170,\"height\":942},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/t5325-b-2s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tyre Changers\",\"item\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/reifenmontiermaschinen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T5325B 2S\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/#website\",\"url\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/\",\"name\":\"John Bean\",\"description\":\"Pioniere der Ausrichtungstechnologie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/#organization\",\"name\":\"John Bean\",\"url\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-logo.png\",\"width\":1000,\"height\":192,\"caption\":\"John Bean\"},\"image\":{\"@id\":\"https:\\\/\\\/www.johnbean.com\\\/eu-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325B 2S | John Bean","description":"Built to get the job done, the John Bean\u00ae T5325B 2S combines all the helpful features you need to change tyres the right way.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/","og_locale":"en_US","og_type":"article","og_title":"Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325B 2S | John Bean","og_description":"Built to get the job done, the John Bean\u00ae T5325B 2S combines all the helpful features you need to change tyres the right way.","og_url":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/","og_site_name":"John Bean","article_modified_time":"2026-04-22T14:42:30+00:00","og_image":[{"width":2170,"height":942,"url":"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-header.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/","url":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/","name":"Reifenmontiermaschine mit pneumatisch kippbarer Montages\u00e4ule T5325B 2S | John Bean","isPartOf":{"@id":"https:\/\/www.johnbean.com\/eu-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/#primaryimage"},"image":{"@id":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/#primaryimage"},"thumbnailUrl":"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-header.jpg","datePublished":"2022-06-14T18:17:01+00:00","dateModified":"2026-04-22T14:42:30+00:00","description":"Built to get the job done, the John Bean\u00ae T5325B 2S combines all the helpful features you need to change tyres the right way.","breadcrumb":{"@id":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/#primaryimage","url":"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-header.jpg","contentUrl":"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2022\/06\/T5325B-2S-header.jpg","width":2170,"height":942},{"@type":"BreadcrumbList","@id":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/t5325-b-2s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.johnbean.com\/eu-de\/"},{"@type":"ListItem","position":2,"name":"Tyre Changers","item":"https:\/\/www.johnbean.com\/eu-de\/reifenmontiermaschinen\/"},{"@type":"ListItem","position":3,"name":"T5325B 2S"}]},{"@type":"WebSite","@id":"https:\/\/www.johnbean.com\/eu-de\/#website","url":"https:\/\/www.johnbean.com\/eu-de\/","name":"John Bean","description":"Pioniere der Ausrichtungstechnologie","publisher":{"@id":"https:\/\/www.johnbean.com\/eu-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.johnbean.com\/eu-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.johnbean.com\/eu-de\/#organization","name":"John Bean","url":"https:\/\/www.johnbean.com\/eu-de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.johnbean.com\/eu-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2021\/12\/cropped-logo.png","contentUrl":"https:\/\/www.johnbean.com\/eu-de\/wp-content\/uploads\/2021\/12\/cropped-logo.png","width":1000,"height":192,"caption":"John Bean"},"image":{"@id":"https:\/\/www.johnbean.com\/eu-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/pages\/8860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/comments?post=8860"}],"version-history":[{"count":116,"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/pages\/8860\/revisions"}],"predecessor-version":[{"id":24867,"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/pages\/8860\/revisions\/24867"}],"up":[{"embeddable":true,"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/pages\/816"}],"wp:attachment":[{"href":"https:\/\/www.johnbean.com\/eu-de\/wp-json\/wp\/v2\/media?parent=8860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}